{"id":33,"count":1,"description":"","link":"https:\/\/autotravelmiami.com\/index.php\/tag\/venezuela\/","name":"VENEZUELA","slug":"venezuela","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VENEZUELA Archives -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/autotravelmiami.com\/index.php\/tag\/venezuela\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VENEZUELA Archives -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/autotravelmiami.com\/index.php\/tag\/venezuela\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/autotravelmiami.com\/index.php\/tag\/venezuela\/\",\"url\":\"https:\/\/autotravelmiami.com\/index.php\/tag\/venezuela\/\",\"name\":\"VENEZUELA Archives -\",\"isPartOf\":{\"@id\":\"https:\/\/autotravelmiami.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/autotravelmiami.com\/index.php\/tag\/venezuela\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/autotravelmiami.com\/index.php\/tag\/venezuela\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/autotravelmiami.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VENEZUELA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/autotravelmiami.com\/#website\",\"url\":\"https:\/\/autotravelmiami.com\/\",\"name\":\"\",\"description\":\"Viajes, Turismo y Diversi\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/autotravelmiami.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VENEZUELA Archives -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/autotravelmiami.com\/index.php\/tag\/venezuela\/","og_locale":"en_US","og_type":"article","og_title":"VENEZUELA Archives -","og_url":"https:\/\/autotravelmiami.com\/index.php\/tag\/venezuela\/","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/autotravelmiami.com\/index.php\/tag\/venezuela\/","url":"https:\/\/autotravelmiami.com\/index.php\/tag\/venezuela\/","name":"VENEZUELA Archives -","isPartOf":{"@id":"https:\/\/autotravelmiami.com\/#website"},"breadcrumb":{"@id":"https:\/\/autotravelmiami.com\/index.php\/tag\/venezuela\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/autotravelmiami.com\/index.php\/tag\/venezuela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/autotravelmiami.com\/"},{"@type":"ListItem","position":2,"name":"VENEZUELA"}]},{"@type":"WebSite","@id":"https:\/\/autotravelmiami.com\/#website","url":"https:\/\/autotravelmiami.com\/","name":"","description":"Viajes, Turismo y Diversi\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/autotravelmiami.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/autotravelmiami.com\/index.php\/wp-json\/wp\/v2\/tags\/33","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autotravelmiami.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/autotravelmiami.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/autotravelmiami.com\/index.php\/wp-json\/wp\/v2\/posts?tags=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}